{"id":207,"date":"2024-10-01T18:09:00","date_gmt":"2024-10-01T18:09:00","guid":{"rendered":"https:\/\/www.cchla.ufpb.br\/inelc2\/?p=207"},"modified":"2025-05-30T00:27:18","modified_gmt":"2025-05-30T00:27:18","slug":"inelc-lanca-nova-identidade-visual","status":"publish","type":"post","link":"https:\/\/www.cchla.ufpb.br\/inelc\/noticia\/inelc-lanca-nova-identidade-visual\/","title":{"rendered":"InELC lan\u00e7a nova identidade visual"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\"><div class=\"linha-header\">Projeto realizado pela empresa j\u00fanior Krisalis muda a cara da logomarca do InELC<\/div><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"http:\/\/www.cchla.ufpb.br\/inelc2\/wp-content\/uploads\/sites\/122\/sites\/260\/2025\/05\/20240916_153043_0000-1.png\" alt=\"\" class=\"wp-image-208\" srcset=\"https:\/\/www.cchla.ufpb.br\/inelc\/wp-content\/uploads\/sites\/122\/sites\/260\/2025\/05\/20240916_153043_0000-1.png 320w, https:\/\/www.cchla.ufpb.br\/inelc\/wp-content\/uploads\/sites\/122\/sites\/260\/2025\/05\/20240916_153043_0000-1-300x300.png 300w, https:\/\/www.cchla.ufpb.br\/inelc\/wp-content\/uploads\/sites\/122\/sites\/260\/2025\/05\/20240916_153043_0000-1-150x150.png 150w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Na sexta-feira, 27 de setembro de 2024, a Dire\u00e7\u00e3o do InELC anunciou o lan\u00e7amento da nova identidade visual do Instituto.&nbsp;O projeto foi realizado atrav\u00e9s de uma parceria firmada entre o InELC e a Empresa J\u00fanior do Curso de Design da UFPB, a Krisalis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nova logomarca \u00e9 mais do que uma simples representa\u00e7\u00e3o gr\u00e1fica: ela expressa a fus\u00e3o de diferentes vozes e ideias, simbolizadas por dois bal\u00f5es que se unem, originando uma forma central, conectiva e din\u00e2mica. Essa uni\u00e3o de elementos destaca a diversidade e pluralidade que guiam o InELC, refletindo nossa miss\u00e3o de ser um agente transformador na maneira como compreendemos e praticamos a comunica\u00e7\u00e3o. Assim, a nova identidade visual refor\u00e7a nosso compromisso de conectar o saber acad\u00eamico \u00e0 sociedade, promovendo o di\u00e1logo cultural e a inova\u00e7\u00e3o.<br><br>Este \u00e9 um marco que celebra nossa trajet\u00f3ria e o futuro que estamos construindo juntos. Convidamos a todos a conhecerem essa nova fase e celebrar conosco!<br><br>Estamos planejando novidades!&nbsp; Juntos, seguimos ampliando horizontes e transformando a educa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Projeto realizado pela empresa j\u00fanior Krisalis muda a cara da logomarca do InELC Na sexta-feira, [&hellip;]<\/p>\n","protected":false},"author":147,"featured_media":208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/users\/147"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":1,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":209,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/posts\/207\/revisions\/209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/media\/208"}],"wp:attachment":[{"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cchla.ufpb.br\/inelc\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}